{"id":1090,"count":1,"description":"","link":"https:\/\/ascoltoattivo.net\/fr\/tag\/comune-di-trento\/","name":"Comune di Trento","slug":"comune-di-trento","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ascoltoattivo.net\/fr\/wp-json\/wp\/v2\/tags\/1090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ascoltoattivo.net\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ascoltoattivo.net\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ascoltoattivo.net\/fr\/wp-json\/wp\/v2\/posts?tags=1090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}